{"id":11069,"date":"2019-12-05T19:00:09","date_gmt":"2019-12-05T22:00:09","guid":{"rendered":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/"},"modified":"2019-12-05T19:00:11","modified_gmt":"2019-12-05T22:00:11","slug":"curso-para-estudos-complementares-com-certificado","status":"publish","type":"post","link":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/","title":{"rendered":"Curso para estudos complementares com certificado"},"content":{"rendered":"<p>Descubra o porqu\u00ea do curso tem a possibilidade de acrescentar a aumentar seu rendimento e at\u00e9 seus conhecimentos. <\/p>\n<p>A perspectiva do mundo corporativo modifica conforme o \u00e2mbito financeiro no qual situa-se o pa\u00eds. <\/p>\n<p>Contudo indiferentemente da etapa que encontra-se o mercado profissional, voc\u00ea tem que ter uma remunera\u00e7\u00e3o fixa para  pagar as suas despesas. <\/p>\n<p>Pois,  as contas n\u00e3o param de vir, voc\u00ea tornando-se assalariado ou n\u00e3o.   <\/p>\n<p>Logo para obter um expediente de trabalho, sendo o expediente de trabalho o primeiro ou n\u00e3o, e inclusive a fim de permanecer atuando, voc\u00ea tem que se destacar dos demais concorrentes. <\/p>\n<p>De que maneira fazer isso: O <a href=\"\/cursos\/administracao\/gestao-no-servico-publico\" > curso<\/a> \u00e9 a op\u00e7\u00e3o vantajosa desse progresso. Todavia n\u00f3s vamos justificar o motivo. <\/p>\n<p><a class=\"btn-ads\" style=\"background-color: #dd4040;\" href=\"\/matricular\/administracao\/gestao-no-servico-publico\">MATRICULAR AGORA<\/a><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-361\"  alt=\"curso\" src=\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-content\/uploads\/2019\/12\/curso-2.jpg\"   width=\"auto\"  > <\/img><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_50 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">O que voc&ecirc; vai ler no texto<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\" role=\"button\"><label for=\"item-6a98831c27a3a\" aria-hidden=\"true\"><span style=\"display: flex;align-items: center;width: 35px;height: 30px;justify-content: center;direction:ltr;\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/label><input  type=\"checkbox\" id=\"item-6a98831c27a3a\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/#Certificado_para_Horas_Complementares\" title=\"Certificado para Horas Complementares\">Certificado para Horas Complementares<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/#Certificado_para_Se_qualificar_para_Concurso\" title=\"Certificado para Se qualificar para Concurso\">Certificado para Se qualificar para Concurso<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/#Como_Sao_os_Treinamentos_do_curso\" title=\"Como S\u00e3o os Treinamentos do  curso\">Como S\u00e3o os Treinamentos do  curso<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/#Resultado_Por_qual_Motivo_Terminar_o_curso\" title=\" Resultado Por qual Motivo Terminar o curso\"> Resultado Por qual Motivo Terminar o curso<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Certificado_para_Horas_Complementares\"><\/span>Certificado para Horas Complementares<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Estudantis necessitam realizar  diversas  pr\u00e1ticas longe da gradua\u00e7\u00e3o, s\u00e3o obrigat\u00f3rias, ou faz ou n\u00e3o se forma! Todo curso tem tuas  especifica\u00e7\u00f5es  a respeito do assunto, contudo uma coisa \u00e9 fato: at\u00e9 o final do curso \u00e9  determinante  fazer todas as Atividades Complementares.<\/p>\n<p>E entre as pr\u00e1ticas que s\u00e3o capazes de ser efetuadas  est\u00e1 o curso de aprimoramento. E a diferen\u00e7a de todas as outras \u00e9 que voc\u00ea consegue realiz\u00e1-lo quando estiver menos atarefado na gradua\u00e7\u00e3o, porque tentar combinar  essas pr\u00e1ticas na \u00e9poca de avalia\u00e7\u00e3o ningu\u00e9m merece, n\u00e3o \u00e9 verdade?<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Certificado_para_Se_qualificar_para_Concurso\"><\/span>Certificado para Se qualificar para Concurso<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Caso voc\u00ea tenha o sonho de possuir  confian\u00e7a no emprego  e ganhar  um ordenado relativamente  \u00f3timo e pensa que com o  concurso voc\u00ea  pode   isto, ent\u00e3o decerto j\u00e1 andou pesquisando e  viu que diversos outros pensam exatamente similar a voc\u00ea, o que  torna o concurso concorrido<\/p>\n<p>S\u00e3o dezenas de livros   acess\u00edveis em com\u00e9rcios, revistarias e em  outros regi\u00f5es,  entretanto eles normalmente s\u00e3o bastante caros. Aqui voc\u00ea  \u00e9 capaz explorar o curso para adquirir conhecimento para concurso p\u00fablico sem gasto.<\/p>\n<p>Essas s\u00e3o  apenas umas das chances pra explorar o certificado, existem in\u00fameras outras. Mas pra  essa conversa n\u00e3o ficar muito longa, j\u00e1 precisamos te  contar as  conveni\u00eancias em ter o certificado do curso.<\/p>\n<p><a class=\"btn-ads\" style=\"background-color: #dd4040;\" href=\"\/matricular\/administracao\/gestao-no-servico-publico\">MATRICULE-SE AGORA<\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Como_Sao_os_Treinamentos_do_curso\"><\/span>Como S\u00e3o os Treinamentos do  curso<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>O curso \u00e9  cedido na plataforma do site na forma de leitura de conte\u00fado. <\/p>\n<p>Dessa maneira, ao se inscrever de forma gr\u00e1tis, o aluno usar\u00e1 o teu login e tua senha a fim de conectar-se a uma  \u00e1rea especial no local que  achar\u00e1 muitos textos indispens\u00e1veis para realizar o curso do in\u00edcio at\u00e9 o fim. <\/p>\n<p>O educando possui  conex\u00e3o de forma infinita ao conte\u00fado, em outras palavras, o educando pode  acessar o website  com o conte\u00fado em PDF sempre.  <\/p>\n<p>O per\u00edodo de treinamento \u00e9 estipulado no come\u00e7o do curso, quanto mais dias voc\u00ea  escolher em se qualificar, maior ser\u00e1 quantidade de conte\u00fado e quantidade de horas no certificado. Fica 100% \u00e0 escolha do discente. <\/p>\n<p>E, at\u00e9 hoje, como o conte\u00fado \u00e9 a dist\u00e2ncia, o lugar e o instante que voc\u00ea vai  fazer tamb\u00e9m fica a tua escolha. Sendo um curso  integralmente modific\u00e1vel. Ent\u00e3o,  ap\u00f3s de realizado o curso, voc\u00ea possui a  op\u00e7\u00e3o de inquirir o certificado.  <\/p>\n<p>O certificado \u00e9 uma declara\u00e7\u00e3o  \u00fatil que vai  validar os  aprendizados  obtidos. Ele \u00e9 bem essencial, j\u00e1 que para executar  qualquer coisa, eles o  pedem.      <\/p>\n<p>Todavia temos custo com fabrica\u00e7\u00e3o e postagem do certificado, n\u00f3s requisitamos uma taxa \u00fanico, esse valor  o qual voc\u00ea  ter\u00e1 com o curso, visto que os materiais did\u00e1ticos, as aulas e o acesso com  docentes especialistas s\u00e3o gr\u00e1tis. Veja onde usar o certificado do curso.  <\/p>\n<p><a class=\"btn-ads\" style=\"background-color: #337ab7;\" href=\"\/matricular\/administracao\/gestao-no-servico-publico\">FAZER ESSE CURSO<\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Resultado_Por_qual_Motivo_Terminar_o_curso\"><\/span> Resultado Por qual Motivo Terminar o curso<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Nesse momento que voc\u00ea j\u00e1 sabe diversas vantagens em efetuar curso. O qual lhe gera a confian\u00e7a de entendimento dentro com as rotinas do emprego e que lhe torna poss\u00edvel o certificado para que voc\u00ea o empregue de diversas probabilidades. Fa\u00e7a que nem os nossos mais de 40 mil educandos que est\u00e3o em todo territ\u00f3rio nacional.      <\/p>\n<p>N\u00e3o perca tempo e \u00e9 somente fazer seu cadastro, come\u00e7ar a qualificar-se e solicitar  teu certificado. \u00d3timos Estudos !<\/p>\n<p><a class=\"btn-ads\" style=\"background-color: #f0ad4e;\" href=\"\/matricular\/administracao\/gestao-no-servico-publico\">FAZER INSCRI\u00c7\u00c3O AGORA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> O per\u00edodo de aprendizagem \u00e9 especificado ao in\u00edcio do curso, quanto mais horas voc\u00ea  optar em estudar, maior ser\u00e1 o n\u00famero de material e o n\u00famero de horas no certificado. Fica totalmente \u00e0 decis\u00e3o do estudante.                            <\/p>\n","protected":false},"author":1,"featured_media":11071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[107,166,2,1389],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Curso para estudos complementares com certificado - Cursos Gratuitos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso para estudos complementares com certificado - Cursos Gratuitos\" \/>\n<meta property=\"og:description\" content=\"O per\u00edodo de aprendizagem \u00e9 especificado ao in\u00edcio do curso, quanto mais horas voc\u00ea optar em estudar, maior ser\u00e1 o n\u00famero de material e o n\u00famero de horas no certificado. Fica totalmente \u00e0 decis\u00e3o do estudante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/\" \/>\n<meta property=\"og:site_name\" content=\"Cursos Gratuitos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cursosrapidosgratis\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-05T22:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-05T22:00:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-content\/uploads\/2019\/12\/curso-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"323\" \/>\n\t<meta property=\"og:image:height\" content=\"323\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Professor do Cursos R\u00e1pidos Gr\u00e1tis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Professor do Cursos R\u00e1pidos Gr\u00e1tis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/\",\"url\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/\",\"name\":\"Curso para estudos complementares com certificado - Cursos Gratuitos\",\"isPartOf\":{\"@id\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/#website\"},\"datePublished\":\"2019-12-05T22:00:09+00:00\",\"dateModified\":\"2019-12-05T22:00:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/#\/schema\/person\/f7121ed0b16ec46972997789aaf55b4e\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso para estudos complementares com certificado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/#website\",\"url\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/\",\"name\":\"Cursos Gratuitos\",\"description\":\"Cursos R\u00e1pidos Gr\u00e1tis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/#\/schema\/person\/f7121ed0b16ec46972997789aaf55b4e\",\"name\":\"Professor do Cursos R\u00e1pidos Gr\u00e1tis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fa0b799eff73f32e2428b13223929bd9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fa0b799eff73f32e2428b13223929bd9?s=96&d=mm&r=g\",\"caption\":\"Professor do Cursos R\u00e1pidos Gr\u00e1tis\"},\"url\":\"https:\/\/www.cursosrapidosgratis.com.br\/blog\/author\/crg-admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curso para estudos complementares com certificado - Cursos Gratuitos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/","og_locale":"pt_BR","og_type":"article","og_title":"Curso para estudos complementares com certificado - Cursos Gratuitos","og_description":"O per\u00edodo de aprendizagem \u00e9 especificado ao in\u00edcio do curso, quanto mais horas voc\u00ea optar em estudar, maior ser\u00e1 o n\u00famero de material e o n\u00famero de horas no certificado. Fica totalmente \u00e0 decis\u00e3o do estudante.","og_url":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/","og_site_name":"Cursos Gratuitos","article_publisher":"https:\/\/www.facebook.com\/cursosrapidosgratis","article_published_time":"2019-12-05T22:00:09+00:00","article_modified_time":"2019-12-05T22:00:11+00:00","og_image":[{"width":323,"height":323,"url":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-content\/uploads\/2019\/12\/curso-3.jpg","type":"image\/jpeg"}],"author":"Professor do Cursos R\u00e1pidos Gr\u00e1tis","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Professor do Cursos R\u00e1pidos Gr\u00e1tis","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/","url":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/","name":"Curso para estudos complementares com certificado - Cursos Gratuitos","isPartOf":{"@id":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/#website"},"datePublished":"2019-12-05T22:00:09+00:00","dateModified":"2019-12-05T22:00:11+00:00","author":{"@id":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/#\/schema\/person\/f7121ed0b16ec46972997789aaf55b4e"},"breadcrumb":{"@id":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/curso-para-estudos-complementares-com-certificado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Curso para estudos complementares com certificado"}]},{"@type":"WebSite","@id":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/#website","url":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/","name":"Cursos Gratuitos","description":"Cursos R\u00e1pidos Gr\u00e1tis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/#\/schema\/person\/f7121ed0b16ec46972997789aaf55b4e","name":"Professor do Cursos R\u00e1pidos Gr\u00e1tis","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fa0b799eff73f32e2428b13223929bd9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fa0b799eff73f32e2428b13223929bd9?s=96&d=mm&r=g","caption":"Professor do Cursos R\u00e1pidos Gr\u00e1tis"},"url":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/author\/crg-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-json\/wp\/v2\/posts\/11069"}],"collection":[{"href":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-json\/wp\/v2\/comments?post=11069"}],"version-history":[{"count":0,"href":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-json\/wp\/v2\/posts\/11069\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-json\/wp\/v2\/media\/11071"}],"wp:attachment":[{"href":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-json\/wp\/v2\/media?parent=11069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-json\/wp\/v2\/categories?post=11069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cursosrapidosgratis.com.br\/blog\/wp-json\/wp\/v2\/tags?post=11069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}